{"id":19890,"date":"2024-07-09T21:05:37","date_gmt":"2024-07-10T05:05:37","guid":{"rendered":"https:\/\/integratechem.com\/tributylcitrat-tbc\/"},"modified":"2025-06-08T17:08:42","modified_gmt":"2025-06-09T01:08:42","slug":"tributyl-citrate-tbc-factory","status":"publish","type":"post","link":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/","title":{"rendered":"Tributylcitrat (TBC)"},"content":{"rendered":"\n<div class=\"wp-block-media-text is-stacked-on-mobile\" style=\"grid-template-columns:19% auto\"><figure class=\"wp-block-media-text__media\"><img data-recalc-dims=\"1\" fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/06\/tributyl-citrate-tbc.jpg?resize=600%2C800&#038;ssl=1\" alt=\"CAS-Nr. 77 89 4 Acetyltriethylcitrat Hersteller und Lieferanten China - Fabrik - Integratechem Co. Ltd \" class=\"wp-image-13097 size-full\" srcset=\"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/06\/tributyl-citrate-tbc.jpg?w=600&amp;ssl=1 600w, https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/06\/tributyl-citrate-tbc.jpg?resize=225%2C300&amp;ssl=1 225w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"\"><strong>Tributylcitrat (TBC)<\/strong> ist ein leistungsstarker, ungiftiger Weichmacher, der allgemein als Ester der Zitronens\u00e4ure bekannt ist. Er erscheint als farblose, \u00f6lige Fl\u00fcssigkeit, die in den meisten organischen L\u00f6sungsmitteln gut l\u00f6slich ist. Mit einem Siedepunkt von 170\u2103 (133,3Pa), einem Flammpunkt (offener Tiegel) von 185\u2103, einem Brechungsindex (25\u2103\/D) von 1,443-1,445 und einer relativen Dichte (25\/25\u2103) von 1,037-1,045 bietet <strong>Tributylcitrat<\/strong> ein vielseitiges Anwendungsspektrum in der Polymerproduktion, einschlie\u00dflich <strong>ungiftigem PVC<\/strong> und anderen Polymersystemen. <strong>Tributylcitrat CAS-Nr. 77-94-1<\/strong> wird wegen seiner Sicherheit, seines Umweltprofils und seiner ausgezeichneten Weichmachereffizienz bevorzugt. <strong>Integratechem<\/strong>, ein f\u00fchrender <strong>Anbieter von Tributylcitrat<\/strong>, liefert hochreines <strong>Tributylcitrat<\/strong> durch fortschrittliche Herstellungsverfahren, die eine hervorragende Qualit\u00e4t f\u00fcr eine breite Palette von Industrien gew\u00e4hrleisten.  <\/p>\n\n\n\n<p class=\"\">Der haupts\u00e4chlich aus Zitronens\u00e4ure und Butanol hergestellte <strong>TBC-Weichmacher<\/strong> ist eine sichere und effiziente Alternative zu herk\u00f6mmlichen Phthalaten und bietet den Vorteil, dass er ungiftig und biologisch abbaubar ist.<\/p>\n<\/div><\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Tributylcitrat Eigenschaften und Spezifikationen<\/strong><\/h3>\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>CAS-Nr.:<\/strong> 77-94-1<\/li>\n\n\n\n<li class=\"\"><strong>Molekulare Formel:<\/strong> C18H32O7<\/li>\n\n\n\n<li class=\"\"><strong>Siedepunkt:<\/strong> 170\u2103 (133.3Pa)<\/li>\n\n\n\n<li class=\"\"><strong>Flammpunkt:<\/strong> 185\u2103<\/li>\n\n\n\n<li class=\"\"><strong>Brechungsindex (25\u2103\/D):<\/strong> 1.443-1.445<\/li>\n\n\n\n<li class=\"\"><strong>Relative Dichte (25\/25\u2103):<\/strong> 1.037-1.045<\/li>\n\n\n\n<li class=\"\"><strong>L\u00f6slichkeit:<\/strong> L\u00f6slich in den meisten organischen L\u00f6sungsmitteln<\/li>\n<\/ul>\n\n<div class=\"wp-block-uagb-container uagb-block-63fcc778 alignfull uagb-is-root-container\"><div class=\"uagb-container-inner-blocks-wrap\">\n<div class=\"wp-block-uagb-container uagb-block-87ace43d\">\n<h3 class=\"wp-block-heading\" id=\"h-what-is-tributyl-citrate-used-for\">Wof\u00fcr wird Tributylcitrat verwendet?<\/h3>\n<\/div>\n\n\n\n<div class=\"wp-block-uagb-container uagb-block-52456680\">\n<p class=\"\">Tributylcitrat (TBC) ist ein Zitronens\u00e4ureester, eine farblose \u00f6lige Fl\u00fcssigkeit, die in den meisten organischen L\u00f6sungsmitteln l\u00f6slich ist. Hersteller von Tributylcitrat (TBC) verwenden Zitronens\u00e4ure und Butanol in Gegenwart eines Katalysators, um Tributylcitrat (TBC) herzustellen. Tributylcitrat (TBC) und sein Nachfolgeprodukt <a href=\"https:\/\/integratechem.com\/de\/acetyl-tributyl-citrate-atbc\/\">Acetyltributylcitrat (ATBC)<\/a> werden als sichere und ungiftige Weichmacher verwendet. Als Weichmacher hat es eine gute L\u00f6slichkeit, \u00d6lbest\u00e4ndigkeit, Lichtbest\u00e4ndigkeit und eine gute Formbest\u00e4ndigkeit. Es ist also gut mit den meisten Zellulosen, Polyvinylchlorid, Polyvinylacetat usw. kompatibel, und wir verwenden TBC haupts\u00e4chlich als Weichmacher f\u00fcr Zelluloseharze und Vinylharze. Wie stellt man <a href=\"https:\/\/integratechem.com\/de\/high-purity-tributyl-citrate-plasticizer\/\" target=\"_blank\" rel=\"noreferrer noopener\">hochreinen Tributylcitrat-Weichmacher<\/a> her? Erstens m\u00fcssen wir eine destillative Trennung vornehmen, zweitens eine neutrale W\u00e4sche, um die S\u00e4urezahl und das Wasser zu reduzieren, um die Hydrolysereaktion zu verringern.      <\/p>\n\n\n\n<p class=\"\"><strong>Tributylcitrat<\/strong> wird \u00fcblicherweise als ungiftiger Weichmacher in einer Vielzahl von Anwendungen eingesetzt, darunter:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>Ungiftige PVC-Granulierung<\/strong>: Der <strong>TBC-Weichmacher<\/strong> wird in gro\u00dfem Umfang bei der Herstellung von ungiftigen PVC-Produkten verwendet und verbessert die Flexibilit\u00e4t und Haltbarkeit bei gleichzeitiger Einhaltung von Gesundheits- und Umweltstandards.<\/li>\n\n\n\n<li class=\"\"><strong>Lebensmittelverpackungen<\/strong>: Seine ungiftige Beschaffenheit macht es ideal f\u00fcr Verpackungsmaterialien, die mit Lebensmitteln in Kontakt kommen.<\/li>\n\n\n\n<li class=\"\"><strong>Medizinische Produkte<\/strong>: <strong>Tributylcitrat<\/strong> wird bei der Herstellung von medizinischen Produkten verwendet, bei denen es auf Sicherheit und Chemikalienbest\u00e4ndigkeit ankommt.<\/li>\n\n\n\n<li class=\"\"><strong>Kinderspielzeug<\/strong>: Die ungiftigen Eigenschaften von <strong>TBC<\/strong> machen es zu einer bevorzugten Wahl f\u00fcr die Herstellung von Spielzeug, da es die mit Weichmachern auf Phthalatbasis verbundenen Risiken eliminiert.<\/li>\n<\/ul>\n<\/div>\n<\/div><\/div>\n\n<h3 class=\"wp-block-heading\"><strong>Anwendungen von Tributylcitrat in Polymeren<\/strong><\/h3>\n\n<p class=\"\"><strong>Tributylcitrat (TBC)<\/strong> wird h\u00e4ufig als Weichmacher in Polymersystemen verwendet, insbesondere bei der Herstellung von <strong>Weich-PVC<\/strong> und Vinylharzen. Zu den Vorteilen von <strong>Tributylcitrat in PVC-Produkten<\/strong> geh\u00f6ren eine verbesserte K\u00e4ltebest\u00e4ndigkeit, eine gute Wasser- und Schimmelbest\u00e4ndigkeit sowie eine erh\u00f6hte Weichmacherwirkung. Dies macht den <strong>TBC-Weichmacher<\/strong> zu einer hochwirksamen und umweltfreundlichen Option f\u00fcr verschiedene Polymere, die eine optimale Leistung sowohl in Industrie- als auch in Verbraucherprodukten gew\u00e4hrleistet.  <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Vorteile von Tributylcitrat in PVC-Produkten<\/strong><\/h3>\n\n<p class=\"\">Im Vergleich zu herk\u00f6mmlichen Weichmachern wie Phthalaten bietet <strong>Tributylcitrat<\/strong> mehrere Vorteile:<\/p>\n\n<ul class=\"wp-block-list\">\n<li class=\"\"><strong>Ungiftig und sicher<\/strong>: Ideal f\u00fcr Produkte, die mit empfindlichen Umgebungen in Ber\u00fchrung kommen, wie z.B. Lebensmittelverpackungen, medizinisches Zubeh\u00f6r und Kinderspielzeug.<\/li>\n\n\n\n<li class=\"\"><strong>Geringe Fl\u00fcchtigkeit und hohe Effizienz<\/strong>: Bietet lang anhaltende Flexibilit\u00e4t und Haltbarkeit f\u00fcr <strong>PVC-Produkte<\/strong>.<\/li>\n\n\n\n<li class=\"\"><strong>Verbesserte Best\u00e4ndigkeit<\/strong>: <strong>Tributylcitrat<\/strong> verbessert die Wasserbest\u00e4ndigkeit, die Schimmelresistenz und die Leistung bei niedrigen Temperaturen in Kunststoffen und eignet sich daher f\u00fcr eine Reihe anspruchsvoller Anwendungen.<\/li>\n\n\n\n<li class=\"\"><strong>Umweltvertr\u00e4glichkeit<\/strong>: Im Gegensatz zu Phthalaten ist <strong>TBC<\/strong> biologisch abbaubar und hat eine geringere Umweltbelastung.<\/li>\n<\/ul>\n\n<h3 class=\"wp-block-heading\"><strong>Vergleichen Sie Tributylcitrat mit anderen Weichmachern<\/strong><\/h3>\n\n<p class=\"\">Beim Vergleich von <strong>Tributylcitrat<\/strong> mit herk\u00f6mmlichen Weichmachern wie <strong>Phthalaten<\/strong> (z.B. DOP, DBP) sticht <strong>TBC<\/strong> durch seine Ungiftigkeit und sein besseres Umweltprofil hervor. W\u00e4hrend Phthalate aufgrund von Gesundheitsbedenken aus dem Verkehr gezogen werden, wird <strong>TBC<\/strong> zunehmend in lebensmitteltechnischen und medizinischen Anwendungen eingesetzt. Dar\u00fcber hinaus bietet der <strong>Weichmacher TBC<\/strong> eine verbesserte Temperatur- und L\u00f6sungsmittelbest\u00e4ndigkeit, was ihn zu einer hervorragenden Alternative f\u00fcr kritische Anwendungen wie Kinderspielzeug und medizinische Ger\u00e4te macht.  <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Tributylcitrat vs. Acetyltributylcitrat<\/strong><\/h3>\n\n<p class=\"\">Sowohl <strong>Tributylcitrat<\/strong> (TBC) als auch <strong>Acetyltributylcitrat (ATBC)<\/strong> sind Weichmacher auf Citratbasis, die in ungiftigen und lebensmitteltauglichen Anwendungen eingesetzt werden. TBC wird haupts\u00e4chlich in PVC, Vinylharzen und anderen Polymeren verwendet. Im Gegensatz dazu ist ATBC besser mit Celluloseacetat kompatibel. Es wird auch wegen seiner h\u00f6heren Flexibilit\u00e4t bei k\u00e4lteren Bedingungen bevorzugt. Die Wahl zwischen TBC und ATBC h\u00e4ngt von den spezifischen Anforderungen des Produkts ab, wie z.B. der Exposition gegen\u00fcber extremen Temperaturen oder dem Bedarf an erh\u00f6hter Flexibilit\u00e4t.    <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Beste Lieferanten von Tributylcitrat und biobasierten Weichmachern<\/strong><\/h3>\n\n<p class=\"\">Wenn Sie auf der Suche nach den <strong>besten Lieferanten f\u00fcr Tributylcitrat<\/strong> sind, bietet <strong>Integratechem<\/strong> un\u00fcbertroffene Qualit\u00e4t und Konsistenz bei der Lieferung von hochreinem <strong>TBC-Weichmacher<\/strong>. Als einer der <strong>f\u00fchrenden Hersteller von biobasierten Weichmachern<\/strong> stellen wir sicher, dass unser <strong>Tributylcitrat<\/strong> die h\u00f6chsten Industriestandards einh\u00e4lt, was es zu einer idealen Wahl f\u00fcr umweltbewusste Hersteller macht. Unsere Produkte helfen Unternehmen, von sch\u00e4dlichen Phthalaten wegzukommen und gleichzeitig hervorragende Weichmachereigenschaften beizubehalten.  <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Wie Sie Phthalate durch Tributylcitrat ersetzen k\u00f6nnen<\/strong><\/h3>\n\n<p class=\"\">Das Ersetzen von Phthalaten durch <strong>Tributylcitrat<\/strong> ist aufgrund seiner hohen Kompatibilit\u00e4t mit Harzen wie <strong>PVC<\/strong> und Vinylharzen ein unkomplizierter Prozess. Es ist eine wirksame Alternative, die mehr Sicherheit und geringere Toxizit\u00e4t bietet, ohne die Weichmacherleistung zu beeintr\u00e4chtigen. Viele Hersteller steigen auf <strong>Citratester-Weichmacher<\/strong> wie <strong>TBC<\/strong> um, um strengeren Umweltvorschriften und der Nachfrage der Verbraucher nach ungiftigen Produkten gerecht zu werden.  <\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Wie synthetisiert man Tributylcitrat (TBC)?<\/strong><\/h3>\n\n<p class=\"\">Die Herstellung von <strong>Tributylcitrat<\/strong> umfasst die Veresterung von Zitronens\u00e4ure mit Butanol in Gegenwart eines Katalysators. Die Schritte umfassen: <\/p>\n\n<ol class=\"wp-block-list\">\n<li class=\"\"><strong>Veresterung<\/strong>: Zitronens\u00e4ure reagiert mit Butanol unter Hitze und einem Katalysator.<\/li>\n\n\n\n<li class=\"\"><strong>Destillation<\/strong>: Menschen Die Reaktionsprodukte werden durch Destillation getrennt, um eine hohe Reinheit zu gew\u00e4hrleisten.<\/li>\n\n\n\n<li class=\"\"><strong>Neutralisieren und Waschen mit Wasser<\/strong>: Diese Verfahren reduzieren die S\u00e4urezahl und beseitigen unerw\u00fcnschte R\u00fcckst\u00e4nde, so dass Sie einen reinen <strong>Tributylcitrat-Weichmacher<\/strong> erhalten.<\/li>\n<\/ol>\n\n<p class=\"\">Bei <strong>Integratechem<\/strong> wenden wir strenge Qualit\u00e4tskontrollma\u00dfnahmen an, um sicherzustellen, dass unser <strong>Tributylcitrat<\/strong> den h\u00f6chsten Reinheits- und Leistungsstandards entspricht.<\/p>\n\n<h3 class=\"wp-block-heading\"><strong>Warum sollten Sie Integratechem als Ihren Tributylcitrat-Lieferanten w\u00e4hlen?<\/strong><\/h3>\n\n<p class=\"\">Wir bei <strong>Integratechem<\/strong> sind bestrebt, <strong>Tributylcitrat<\/strong> und andere Citratester-Weichmacher in Spitzenqualit\u00e4t zu liefern. Mit jahrelanger Erfahrung und einem engagierten F&amp;E-Team gew\u00e4hrleisten wir h\u00f6chste Produktreinheit und Kundenzufriedenheit. Ganz gleich, ob Sie <strong>Tributylcitrat<\/strong> f\u00fcr die Industrie, f\u00fcr medizinische Produkte oder f\u00fcr die Herstellung von Polymeren ben\u00f6tigen, wir bieten Ihnen wettbewerbsf\u00e4hige Preise und einen zuverl\u00e4ssigen Service, der Ihre Anforderungen erf\u00fcllt.  <\/p>\n\n<p class=\"\">Wenn Sie weitere Informationen zu <strong>Tributylcitrat CAS-Nr. 77-94-1<\/strong> w\u00fcnschen oder Fragen zur Produktverf\u00fcgbarkeit haben, kontaktieren Sie uns noch heute. Lassen Sie <strong>Integratechem<\/strong> Ihr zuverl\u00e4ssiger Partner und Lieferant f\u00fcr <strong>TBC-Weichmacher<\/strong> sein. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-faq\">FAQ<\/h2>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Was ist Tributylcitrat (TBC)?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-what-is-tbc\"><strong>Was ist TBC?<\/strong><\/h3>\n\n\n\n<p class=\"\">Kurz gesagt, TBC ist ein Zitronens\u00e4ureester, eine farblose \u00f6lige Fl\u00fcssigkeit, die in den meisten organischen L\u00f6sungsmitteln l\u00f6slich ist. Die Hersteller von Tributylcitrat (TBC) verwenden Zitronens\u00e4ure und Butanol in Gegenwart eines Katalysators, um TBC herzustellen. Dar\u00fcber hinaus hat die US FDA TBC und sein Folgeprodukt Acetyltributylcitrat (ATBC) als sichere und ungiftige Weichmacher zugelassen.  <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Wie werden Ester klassifiziert?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-how-are-esters-classified\"><strong>Wie werden Ester klassifiziert?<\/strong><\/h3>\n\n\n\n<p class=\"\">Nach der chemischen Struktur. Man unterteilt sie in: (1) Phthalatester; (2) aliphatische zweibasige S\u00e4ureester; (3) Phosphatester; (4) Epoxyverbindungen; (5) polymere Weichmacher; (6) Benzolpolyester; (7) chlorhaltige Weichmacher; (8) Alkylsulfonatester; (9) Polyolester; (10) andere Weichmacher. <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Wie wird Tributylcitrat (TBC) hergestellt?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-how-factories-to-produce-tbc\"><strong>Wie <\/strong>produzieren Fabriken <strong>TBC?<\/strong><\/h3>\n\n\n\n<p class=\"\">Zitronens\u00e4ure reagiert mit Butylalkohol durch eine Veresterungsreaktion sowie eine destillative Reinigung unter der Einwirkung eines Katalysators, um Zitratester zu erzeugen.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>M\u00fcssen Esterverbindungen neutralisiert und mit Wasser gewaschen werden, um den Katalysator nach der Veresterung zu entfernen?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-is-it-necessary-to-neutralize-and-wash-with-water-to-remove-the-catalyst\"><strong>Ist es notwendig, den Katalysator zu neutralisieren und mit Wasser zu waschen, um ihn zu entfernen?<\/strong><\/h3>\n\n\n\n<p class=\"\">Wenn die Hersteller einen Katalysator verwenden, der eine gute katalytische Aktivit\u00e4t aufweist und aus dem System entfernt werden kann, dann muss er nicht neutralisiert und mit Wasser gewaschen werden, oder einen Katalysator, der bei der Reaktionstemperatur eine homogene Phase mit dem Ester bildet und sich nach dem Absenken der Temperatur in einem festen Zustand niederschl\u00e4gt.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Was ist Veresterung?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-what-is-esterification\"><strong>Was ist Veresterung?<\/strong><\/h3>\n\n\n\n<p class=\"\">In der Tat reagiert die Carbons\u00e4ure in Gegenwart einiger weniger Katalysatoren (konzentrierte Schwefels\u00e4ure, trockener Chlorwasserstoff, Ionenaustauscherharz vom Typ starke S\u00e4ure) mit Alkohol und bildet Ester. Daher nennen die Hersteller diese Reaktion Veresterung. Kurz gesagt, die Veresterung ist eine reversible Reaktion, und wenn sich ein Gleichgewicht einstellt, ist eine bestimmte Anzahl von Reaktanten und Produkten vorhanden.  <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Was sind die funktionellen Gruppen von Citratestern?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-what-are-the-functional-groups-of-citrate-esters\"><strong>Was sind die funktionellen Gruppen von Citratestern?<\/strong><\/h3>\n\n\n\n<p class=\"\">Die funktionelle Gruppe von Citratestern ist ebenfalls -COO-. Durch Dehydratisierung der Carboxylgruppe (-COOH) und der Hydroxylgruppe (-OH) entsteht sie in der Tat. <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Was sind die Anwendungsgebiete von Tributylcitrat (TBC)?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-what-are-the-applications-of-tbc\"><strong>Was sind die Anwendungen von TBC<\/strong><\/h3>\n\n\n\n<p class=\"\">In der Tat hat die US FDA die wichtigsten Sorten von TBC und Acetyl ATBC als sichere und ungiftige Weichmacher zugelassen. Dar\u00fcber hinaus ist Citratester als Weichmacher sehr gut l\u00f6slich, \u00f6l- und lichtbest\u00e4ndig und hat eine gute Schimmelbest\u00e4ndigkeit. Au\u00dferdem ist er gut mit den meisten Zellulosen, Polyvinylchlorid, Polyvinylacetat usw. kompatibel. Au\u00dferdem wird TBC haupts\u00e4chlich als Weichmacher f\u00fcr Celluloseharze und Vinylharze verwendet. Vor allem aber ist TBC der Rohstoff f\u00fcr die Herstellung von <a href=\"https:\/\/en.wikipedia.org\/wiki\/Acetyltributylcitrate\" target=\"_blank\" rel=\"noreferrer noopener\">ATBC<\/a>.    <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong><strong>Wie <\/strong><strong> berechnet<\/strong> man<strong> die urspr\u00fcngliche Verbrauchsmenge von Tributylcitrat (TBC)?<\/strong><\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-how-to-calculate-the-original-consumption-ratio-of-tbc\"><strong><strong>Wie <\/strong><strong> berechnet<\/strong> man<strong> die urspr\u00fcngliche Verbrauchsquote von TBC?<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"\">Die Lieferanten in China berechnen die Reaktion wie folgt: Zitronens\u00e4ure ist eine Tricarbons\u00e4ure. Ein Molek\u00fcl Zitronens\u00e4ure reagiert mit drei Molek\u00fclen Monol, um ein Molek\u00fcl TBC zu erzeugen. Durch Multiplikation der Koeffizienten f\u00fcr die Reaktion mit ihren Molekulargewichten bestimmen sie das Verh\u00e4ltnis des Rohstoffverbrauchs. Daher spiegelt das Verh\u00e4ltnis zwischen den drei Produkten das Verh\u00e4ltnis des Rohstoffverbrauchs wider.   <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Welches ist der am h\u00e4ufigsten verwendete kosteng\u00fcnstige Weichmacher-Ester?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-commonly-used-and-cost-effective-plasticizer\"><strong>H\u00e4ufig verwendeter und kosteng\u00fcnstiger Weichmacher<\/strong><\/h3>\n\n\n\n<p class=\"\">Die Hersteller sind n\u00e4mlich der Meinung, dass die kosteng\u00fcnstigsten Weichmacher Dibutylphthalat und Dioctylphthalat sind.<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Welche Ester k\u00f6nnen als M\u00fcckenschutzmittel verwendet werden?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-what-esters-w-e-can-use-as-mosquito-repellents\"><strong>Welche Ester wir<\/strong> <strong>als M\u00fcckenschutzmittel verwenden<\/strong> <strong>k\u00f6nnen<\/strong> <\/h3>\n\n\n\n<p class=\"\">Der von Lieferanten in China angebotene Ester ist Dimethylphthalat<\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Wie werden Ester chemisch benannt?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-how-do-we-chemically-name-esters\"><strong>Wie benennt man Ester chemisch?<\/strong><\/h3>\n\n\n\n<p class=\"\">Kurz gesagt, dem Wort &#8220;Ester&#8221; k\u00f6nnen die entsprechenden Namen von Carbons\u00e4uren und Alkoholen vorangestellt werden. Das Wort &#8220;Alkohol&#8221; kann im Allgemeinen weggelassen werden, d.h. &#8220;einige&#8221; S\u00e4ure &#8220;einige&#8221; Ester. Aber der Ester von Polyolen, in der Regel setzen die &#8220;S\u00e4ure hinter, genannt&#8221; ein Alkohol ein S\u00e4ureester.&#8221;  <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Wie l\u00e4sst sich die Ausbeute an Ester erh\u00f6hen?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-how-to-increase-the-yield-of-ester\"><strong>Wie l\u00e4sst sich die Ausbeute an Ester erh\u00f6hen?<\/strong><\/h3>\n\n\n\n<p class=\"\">In Fabriken wird die Reaktion durch Erhitzen und Hinzuf\u00fcgen eines Katalysators lediglich beschleunigt. Dies \u00e4ndert jedoch nichts an der Zusammensetzung des ausgewogenen Materials. Um die Esterausbeute zu erh\u00f6hen, f\u00fcgen Hersteller und Lieferanten in China oft zus\u00e4tzliche Carbons\u00e4uren und Alkohole hinzu. Sie entfernen auch das w\u00e4hrend der Reaktion gebildete Wasser. Wenn der produzierte Ester einen niedrigen Siedepunkt hat, k\u00f6nnen die Fabriken den Ester mit Dampf aus der Mischung entfernen. Dadurch verschiebt sich das Gleichgewicht und die Esterausbeute wird verbessert. Bei der industriellen Herstellung von Ethylacetat zum Beispiel verwenden die Fabriken \u00fcbersch\u00fcssige Essigs\u00e4ure. Sie dampfen das Azeotrop aus Ethylacetat und Wasser aus (Wasser 8,6%, Ethylacetat 91,4%, konstanter Siedepunkt 70,45\u2103). Dadurch verschiebt sich das Gleichgewicht. Die Fabriken f\u00fcgen dann mehr Essigs\u00e4ure und Ethanol hinzu und fahren fort, Ethylacetat und Wasser f\u00fcr eine kontinuierliche Produktion zu verdampfen.         <\/p>\n<\/details>\n\n<details class=\"wp-block-details is-layout-flow wp-block-details-is-layout-flow\"><summary><strong>Was ist Verseifung?<\/strong><\/summary>\n<h3 class=\"wp-block-heading\" id=\"h-what-is-saponification\"><strong>Was ist Verseifung?<\/strong><\/h3>\n\n\n\n<p class=\"\">Der Volksmund bezeichnet die Hydrolyse von Estern in alkalischer L\u00f6sung als Verseifungsreaktion. Der Grund daf\u00fcr ist, dass das fortgeschrittene Fetts\u00e4uresalz, das durch die alkalische Hydrolyse von Fett gewonnen wird, der Grund f\u00fcr die Seife ist. <\/p>\n<\/details>\n\n<p style=\"margin-top:0;margin-bottom:0\" class=\"\">Kategorie: <a href=\"https:\/\/integratechem.com\/de\/category\/citrate-esters-de\/\">Zitrat-Ester<\/a><\/p>\n\n<p style=\"margin-top:0;margin-bottom:0\" class=\"\">Hei\u00dfe Tags: Citratester-Weichmacher, Beste Lieferanten von Tributylcitrat, CAS-Nr. 77-94-1, <a href=\"https:\/\/integratechem.com\/de\/tag\/atbc-de\/\">ATBC<\/a>, <a href=\"https:\/\/integratechem.com\/de\/tag\/non-toxic-plasticizer-de\/\">Ungiftiger Weichmacher<\/a>, <a href=\"https:\/\/integratechem.com\/de\/tag\/plasticizer-for-cellulose-resins-de\/\">Weichmacher f\u00fcr Zelluloseharze<\/a>, <a href=\"https:\/\/integratechem.com\/de\/tag\/pvc-plasticizer-de\/\">PVC-Weichmacher<\/a>, <a href=\"https:\/\/integratechem.com\/de\/tag\/tributyl-ester-de\/\">Tributyl-Ester<\/a><\/p>\n\n<p style=\"margin-top:0;margin-bottom:0\" class=\"\">Verwandte Links: <a href=\"https:\/\/integratechem.com\/de\/high-quality-plasticizer-tbc-tributyl-citrate\/\">Hochwertiger Weichmacher TBC Tributyl Citrate<\/a>, <a href=\"https:\/\/integratechem.com\/de\/cas-no-77-94-1\/\">CAS Nr. 77 94 1<\/a>, <a href=\"https:\/\/integratechem.com\/de\/dimethyl-adipate\/\">Dimethyl Adipate<\/a>, <a href=\"https:\/\/integratechem.com\/de\/acetyl-tributyl-citrate\/\">Acetyl Tributyl Citrate<\/a><\/p>\n\n<p class=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tributylcitrat (TBC) ist ein Ester der Zitronens\u00e4ure, eine farblose \u00f6lige Fl\u00fcssigkeit. Und es ist in den meisten organischen L\u00f6sungsmitteln l\u00f6slich. Mit einem Siedepunkt von 170\u2103 (133,3Pa), einem Flammpunkt (offener Tiegel) von 185\u2103, einem Brechungsindex (25\u2103\/D) von 1,443-1,445 und einer relativen Dichte (25\/25\u2103) von 1,037-1,045 ist es vor allem ein ungiftiger Weichmacher. Tributylcitrat-Weichmacher kann also zum Granulieren von ungiftigem PVC und zur Herstellung von Verpackungsmaterial f\u00fcr Lebensmittel verwendet werden. Normalerweise wird Tributylcitrat (TBC) unter Verwendung von Zitronens\u00e4ure und Butanol hergestellt.      <\/p>\n","protected":false},"author":2,"featured_media":17460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"nf_dc_page":"","_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[688],"tags":[704,727,733,726,730],"class_list":["post-19890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-citrate-esters-de","tag-atbc-de","tag-pvc-plasticizer-de","tag-tributyl-ester-de","tag-non-toxic-plasticizer-de","tag-plasticizer-for-cellulose-resins-de"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tributylcitrat (TBC) Hersteller und Lieferanten China - Fabrik - Weifang Integratechem Co., Ltd.<\/title>\n<meta name=\"description\" content=\"Integratechem bietet Tributylcitrat (tbc) zum g\u00fcnstigsten Preis an. Als einer der f\u00fchrenden und professionellen Hersteller und Lieferanten in China zeichnen wir uns durch h\u00f6chste Qualit\u00e4t, hohe Effizienz und gute Stabilit\u00e4t aus. Willkommen in unserer Fabrik zum Kauf.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tributylcitrat (TBC)\" \/>\n<meta property=\"og:description\" content=\"Integratechem bietet Tributylcitrat (tbc) zum g\u00fcnstigsten Preis an. Als einer der f\u00fchrenden und professionellen Hersteller und Lieferanten in China zeichnen wir uns durch h\u00f6chste Qualit\u00e4t, hohe Effizienz und gute Stabilit\u00e4t aus. Willkommen in unserer Fabrik zum Kauf.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/\" \/>\n<meta property=\"og:site_name\" content=\"Weifang Integratechem Co., Ltd.\" \/>\n<meta property=\"article:published_time\" content=\"2024-07-10T05:05:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-09T01:08:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"467\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Hongjian Wang\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hongjian Wang\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"10\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/\"},\"author\":{\"name\":\"Hongjian Wang\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#\\\/schema\\\/person\\\/bf11938f009df4efa1e3a405a1737367\"},\"headline\":\"Tributylcitrat (TBC)\",\"datePublished\":\"2024-07-10T05:05:37+00:00\",\"dateModified\":\"2025-06-09T01:08:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/\"},\"wordCount\":1980,\"publisher\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/integratechem.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1\",\"keywords\":[\"ATBC\",\"PVC-Weichmacher\",\"Tributylester\",\"Ungiftiger Weichmacher\",\"Weichmacher f\u00fcr Celluloseharze\"],\"articleSection\":[\"Citratester\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/\",\"url\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/\",\"name\":\"Tributylcitrat (TBC) Hersteller und Lieferanten China - Fabrik - Weifang Integratechem Co., Ltd.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/integratechem.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1\",\"datePublished\":\"2024-07-10T05:05:37+00:00\",\"dateModified\":\"2025-06-09T01:08:42+00:00\",\"description\":\"Integratechem bietet Tributylcitrat (tbc) zum g\u00fcnstigsten Preis an. Als einer der f\u00fchrenden und professionellen Hersteller und Lieferanten in China zeichnen wir uns durch h\u00f6chste Qualit\u00e4t, hohe Effizienz und gute Stabilit\u00e4t aus. Willkommen in unserer Fabrik zum Kauf.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/integratechem.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/integratechem.com\\\/wp-content\\\/uploads\\\/2024\\\/07\\\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1\",\"width\":350,\"height\":467,\"caption\":\"CAS 77-94-1 by Integratechem - Bio-based plasticizer with 185\u2103 flash point for FDA\\\/EU compliant applications.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/tributyl-citrate-tbc-factory\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/integratechem.com\\\/de\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Citratester\",\"item\":\"https:\\\/\\\/integratechem.com\\\/de\\\/category\\\/citrate-esters-de\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Tributylcitrat (TBC)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/integratechem.com\\\/de\\\/\",\"name\":\"Weifang Integratechem Co., Ltd.\",\"description\":\"Organic Esters Manufacturers and Suppliers China - Factory - Integratechem\",\"publisher\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#organization\"},\"alternateName\":\"Integratechem\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/integratechem.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#organization\",\"name\":\"Weifang Integratechem Co., Ltd.\",\"alternateName\":\"Integratechem\",\"url\":\"https:\\\/\\\/integratechem.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/integratechem.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_v1.0.png?fit=613%2C148&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/integratechem.com\\\/wp-content\\\/uploads\\\/2022\\\/04\\\/Logo_v1.0.png?fit=613%2C148&ssl=1\",\"width\":613,\"height\":148,\"caption\":\"Weifang Integratechem Co., Ltd.\"},\"image\":{\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"description\":\"Weifang Integrated Chemical Co., Ltd is located in Weifang City, China. We are a leading, experienced and professional supplier of organic ester chemicals. Currently, we produce and supply a series of organic ester products, which are used as solvents, plasticizers and organic synthesis intermediates for the production of coatings, inks, adhesives, plastics, resins, rubber, pesticides, etc. We are continuously committed to providing customers with high-quality products, competitive prices and continuous services to meet customer needs. Over the years, our products have been exported to Asia, Europe, the Middle East, America and other countries and regions, and have been well received by users and have won a good reputation. We work closely with our customers to deliver products and solutions that create value and competitive advantage. Companies or organizations from all over the world are warmly welcome to contact us to discuss business and cooperation.\",\"email\":\"info@integratechem.com\",\"telephone\":\"+86 536 8956913\",\"legalName\":\"Weifang Integratechem Co., Ltd.\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/integratechem.com\\\/de\\\/#\\\/schema\\\/person\\\/bf11938f009df4efa1e3a405a1737367\",\"name\":\"Hongjian Wang\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5af6846955a8e629b79586213983852656e71ba16e252fc61fff6e4baa682c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5af6846955a8e629b79586213983852656e71ba16e252fc61fff6e4baa682c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f5af6846955a8e629b79586213983852656e71ba16e252fc61fff6e4baa682c9?s=96&d=mm&r=g\",\"caption\":\"Hongjian Wang\"},\"sameAs\":[\"http:\\\/\\\/integratechem.com\"],\"url\":\"https:\\\/\\\/integratechem.com\\\/de\\\/author\\\/wanghongjian1088\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tributylcitrat (TBC) Hersteller und Lieferanten China - Fabrik - Weifang Integratechem Co., Ltd.","description":"Integratechem bietet Tributylcitrat (tbc) zum g\u00fcnstigsten Preis an. Als einer der f\u00fchrenden und professionellen Hersteller und Lieferanten in China zeichnen wir uns durch h\u00f6chste Qualit\u00e4t, hohe Effizienz und gute Stabilit\u00e4t aus. Willkommen in unserer Fabrik zum Kauf.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/","og_locale":"de_DE","og_type":"article","og_title":"Tributylcitrat (TBC)","og_description":"Integratechem bietet Tributylcitrat (tbc) zum g\u00fcnstigsten Preis an. Als einer der f\u00fchrenden und professionellen Hersteller und Lieferanten in China zeichnen wir uns durch h\u00f6chste Qualit\u00e4t, hohe Effizienz und gute Stabilit\u00e4t aus. Willkommen in unserer Fabrik zum Kauf.","og_url":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/","og_site_name":"Weifang Integratechem Co., Ltd.","article_published_time":"2024-07-10T05:05:37+00:00","article_modified_time":"2025-06-09T01:08:42+00:00","og_image":[{"width":350,"height":467,"url":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1","type":"image\/jpeg"}],"author":"Hongjian Wang","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Hongjian Wang","Gesch\u00e4tzte Lesezeit":"10\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/#article","isPartOf":{"@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/"},"author":{"name":"Hongjian Wang","@id":"https:\/\/integratechem.com\/de\/#\/schema\/person\/bf11938f009df4efa1e3a405a1737367"},"headline":"Tributylcitrat (TBC)","datePublished":"2024-07-10T05:05:37+00:00","dateModified":"2025-06-09T01:08:42+00:00","mainEntityOfPage":{"@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/"},"wordCount":1980,"publisher":{"@id":"https:\/\/integratechem.com\/de\/#organization"},"image":{"@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1","keywords":["ATBC","PVC-Weichmacher","Tributylester","Ungiftiger Weichmacher","Weichmacher f\u00fcr Celluloseharze"],"articleSection":["Citratester"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/","url":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/","name":"Tributylcitrat (TBC) Hersteller und Lieferanten China - Fabrik - Weifang Integratechem Co., Ltd.","isPartOf":{"@id":"https:\/\/integratechem.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/#primaryimage"},"image":{"@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1","datePublished":"2024-07-10T05:05:37+00:00","dateModified":"2025-06-09T01:08:42+00:00","description":"Integratechem bietet Tributylcitrat (tbc) zum g\u00fcnstigsten Preis an. Als einer der f\u00fchrenden und professionellen Hersteller und Lieferanten in China zeichnen wir uns durch h\u00f6chste Qualit\u00e4t, hohe Effizienz und gute Stabilit\u00e4t aus. Willkommen in unserer Fabrik zum Kauf.","breadcrumb":{"@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/#primaryimage","url":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1","contentUrl":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1","width":350,"height":467,"caption":"CAS 77-94-1 by Integratechem - Bio-based plasticizer with 185\u2103 flash point for FDA\/EU compliant applications."},{"@type":"BreadcrumbList","@id":"https:\/\/integratechem.com\/de\/tributyl-citrate-tbc-factory\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/integratechem.com\/de\/home\/"},{"@type":"ListItem","position":2,"name":"Citratester","item":"https:\/\/integratechem.com\/de\/category\/citrate-esters-de\/"},{"@type":"ListItem","position":3,"name":"Tributylcitrat (TBC)"}]},{"@type":"WebSite","@id":"https:\/\/integratechem.com\/de\/#website","url":"https:\/\/integratechem.com\/de\/","name":"Weifang Integratechem Co., Ltd.","description":"Organic Esters Manufacturers and Suppliers China - Factory - Integratechem","publisher":{"@id":"https:\/\/integratechem.com\/de\/#organization"},"alternateName":"Integratechem","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/integratechem.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/integratechem.com\/de\/#organization","name":"Weifang Integratechem Co., Ltd.","alternateName":"Integratechem","url":"https:\/\/integratechem.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/integratechem.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2022\/04\/Logo_v1.0.png?fit=613%2C148&ssl=1","contentUrl":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2022\/04\/Logo_v1.0.png?fit=613%2C148&ssl=1","width":613,"height":148,"caption":"Weifang Integratechem Co., Ltd."},"image":{"@id":"https:\/\/integratechem.com\/de\/#\/schema\/logo\/image\/"},"description":"Weifang Integrated Chemical Co., Ltd is located in Weifang City, China. We are a leading, experienced and professional supplier of organic ester chemicals. Currently, we produce and supply a series of organic ester products, which are used as solvents, plasticizers and organic synthesis intermediates for the production of coatings, inks, adhesives, plastics, resins, rubber, pesticides, etc. We are continuously committed to providing customers with high-quality products, competitive prices and continuous services to meet customer needs. Over the years, our products have been exported to Asia, Europe, the Middle East, America and other countries and regions, and have been well received by users and have won a good reputation. We work closely with our customers to deliver products and solutions that create value and competitive advantage. Companies or organizations from all over the world are warmly welcome to contact us to discuss business and cooperation.","email":"info@integratechem.com","telephone":"+86 536 8956913","legalName":"Weifang Integratechem Co., Ltd."},{"@type":"Person","@id":"https:\/\/integratechem.com\/de\/#\/schema\/person\/bf11938f009df4efa1e3a405a1737367","name":"Hongjian Wang","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/f5af6846955a8e629b79586213983852656e71ba16e252fc61fff6e4baa682c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f5af6846955a8e629b79586213983852656e71ba16e252fc61fff6e4baa682c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f5af6846955a8e629b79586213983852656e71ba16e252fc61fff6e4baa682c9?s=96&d=mm&r=g","caption":"Hongjian Wang"},"sameAs":["http:\/\/integratechem.com"],"url":"https:\/\/integratechem.com\/de\/author\/wanghongjian1088\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1","uagb_featured_image_src":{"full":["https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1",350,467,false],"thumbnail":["https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?resize=150%2C150&ssl=1",150,150,true],"medium":["https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=225%2C300&ssl=1",225,300,true],"medium_large":["https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1",350,467,true],"large":["https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1",350,467,true],"1536x1536":["https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1",350,467,true],"2048x2048":["https:\/\/i0.wp.com\/integratechem.com\/wp-content\/uploads\/2024\/07\/tributyl-citrate-tbc.jpg?fit=350%2C467&ssl=1",350,467,true]},"uagb_author_info":{"display_name":"Hongjian Wang","author_link":"https:\/\/integratechem.com\/de\/author\/wanghongjian1088\/"},"uagb_comment_info":0,"uagb_excerpt":"Tributylcitrat (TBC) ist ein Ester der Zitronens\u00e4ure, eine farblose \u00f6lige Fl\u00fcssigkeit. Und es ist in den meisten organischen L\u00f6sungsmitteln l\u00f6slich. Mit einem Siedepunkt von 170\u2103 (133,3Pa), einem Flammpunkt (offener Tiegel) von 185\u2103, einem Brechungsindex (25\u2103\/D) von 1,443-1,445 und einer relativen Dichte (25\/25\u2103) von 1,037-1,045 ist es vor allem ein ungiftiger Weichmacher. Tributylcitrat-Weichmacher kann also zum&hellip;","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/posts\/19890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/comments?post=19890"}],"version-history":[{"count":5,"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/posts\/19890\/revisions"}],"predecessor-version":[{"id":25323,"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/posts\/19890\/revisions\/25323"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/media\/17460"}],"wp:attachment":[{"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/media?parent=19890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/categories?post=19890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/integratechem.com\/de\/wp-json\/wp\/v2\/tags?post=19890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}